{"id":986,"date":"2012-01-06T10:21:51","date_gmt":"2012-01-06T08:21:51","guid":{"rendered":"http:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309.jpg"},"modified":"2012-01-06T10:21:51","modified_gmt":"2012-01-06T08:21:51","slug":"aventura-309","status":"inherit","type":"attachment","link":"https:\/\/www.travellermagazin.ro\/arhiva\/2012\/01\/06\/o-tura-de-aventura-printre-trifoi-si-tigai\/aventura-309\/","title":{"rendered":"Aventura 309"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-986","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<a  href='https:\/\/www.travellermagazin.ro\/arhiva\/wp-admin\/options-general.php?page=post_views' class='entry-meta' style='text-align:center'><b>Post Views<\/a><\/b> = 390<br\/><p class=\"attachment\"><a href='https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-225x300.jpg 225w, https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-768x1024.jpg 768w, https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309.jpg 1536w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Post Views = 390<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1536","height":"2048","hwstring_small":"height='96' width='72'","file":"2012\/01\/Aventura-309.jpg","sizes":{"thumbnail":{"file":"Aventura-309-150x150.jpg","width":"150","height":"150","source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-150x150.jpg"},"medium":{"file":"Aventura-309-225x300.jpg","width":"225","height":"300","source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-225x300.jpg"},"large":{"file":"Aventura-309-768x1024.jpg","width":"768","height":"1024","source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-768x1024.jpg"},"post-thumbnail":{"file":"Aventura-309-940x198.jpg","width":"940","height":"198","source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309-940x198.jpg"},"full":{"file":"Aventura-309.jpg","width":1536,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"Canon PowerShot G6","caption":"","created_timestamp":"1321792093","copyright":"","focal_length":"7.1875","iso":"0","shutter_speed":"0.003125","title":""}},"post":940,"source_url":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-content\/uploads\/2012\/01\/Aventura-309.jpg","_links":{"self":[{"href":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-json\/wp\/v2\/media\/986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.travellermagazin.ro\/arhiva\/wp-json\/wp\/v2\/comments?post=986"}]}}